{"id":9157,"date":"2024-03-25T05:51:17","date_gmt":"2024-03-25T05:51:17","guid":{"rendered":"https:\/\/abpon.freshdigitalthailand.com\/product\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\/"},"modified":"2024-03-25T05:57:45","modified_gmt":"2024-03-25T05:57:45","slug":"%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600","status":"publish","type":"product","link":"https:\/\/www.abpon.com\/en\/product\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\/","title":{"rendered":"Elbow\u00a045degree\u00a0SUS\u00a0316\u00a0#10\u00a06&#8243;"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":89338,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[8860,8865,8776],"product_tag":[],"class_list":{"0":"post-9157","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-005_013-en","7":"product_cat-005_013_005-en","8":"product_cat-5-en","9":"pa_coating-plain","10":"pa_code-unit-pcs","11":"pa_connecting-9162","12":"pa_group-code-9507","13":"pa_material-sus316","14":"pa_packing-quantity-9154","15":"pa_pipe-size-9224","16":"pa_sales-unit-9155","17":"pa_standard-sch10","19":"first","20":"instock","21":"purchasable","22":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elbow\u00a045degree\u00a0SUS\u00a0316\u00a0#10\u00a06&quot; - Abpon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abpon.com\/product\/\u0e02\u0e49\u0e2d\u0e07\u0e2d\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21-jef-sus31610-45\u0e2d\u0e07\u0e28\u0e32-041645-600\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elbow\u00a045degree\u00a0SUS\u00a0316\u00a0#10\u00a06&quot; - Abpon\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abpon.com\/product\/\u0e02\u0e49\u0e2d\u0e07\u0e2d\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21-jef-sus31610-45\u0e2d\u0e07\u0e28\u0e32-041645-600\/\" \/>\n<meta property=\"og:site_name\" content=\"Abpon\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-25T05:57:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abpon.com\\\/product\\\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\\\/\",\"url\":\"https:\\\/\\\/www.abpon.com\\\/product\\\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\\\/\",\"name\":\"Elbow\u00a045degree\u00a0SUS\u00a0316\u00a0#10\u00a06\\\" - Abpon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abpon.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abpon.com\\\/product\\\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abpon.com\\\/product\\\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abpon.com\\\/wp-content\\\/uploads\\\/041645-600.png\",\"datePublished\":\"2024-03-25T05:51:17+00:00\",\"dateModified\":\"2024-03-25T05:57:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abpon.com\\\/product\\\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abpon.com\\\/product\\\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.abpon.com\\\/product\\\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abpon.com\\\/wp-content\\\/uploads\\\/041645-600.png\",\"contentUrl\":\"https:\\\/\\\/www.abpon.com\\\/wp-content\\\/uploads\\\/041645-600.png\",\"width\":600,\"height\":600,\"caption\":\"041645 600\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abpon.com\\\/product\\\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abpon.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.abpon.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Elbow\u00a045degree\u00a0SUS\u00a0316\u00a0#10\u00a06&#8243;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abpon.com\\\/#website\",\"url\":\"https:\\\/\\\/www.abpon.com\\\/\",\"name\":\"Abpon\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abpon.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abpon.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abpon.com\\\/#organization\",\"name\":\"Abpon\",\"url\":\"https:\\\/\\\/www.abpon.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.abpon.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.abpon.com\\\/wp-content\\\/uploads\\\/09-abpon-logo-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/www.abpon.com\\\/wp-content\\\/uploads\\\/09-abpon-logo-removebg-preview.png\",\"width\":276,\"height\":183,\"caption\":\"Abpon\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abpon.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elbow\u00a045degree\u00a0SUS\u00a0316\u00a0#10\u00a06\" - Abpon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abpon.com\/product\/\u0e02\u0e49\u0e2d\u0e07\u0e2d\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21-jef-sus31610-45\u0e2d\u0e07\u0e28\u0e32-041645-600\/","og_locale":"en_US","og_type":"article","og_title":"Elbow\u00a045degree\u00a0SUS\u00a0316\u00a0#10\u00a06\" - Abpon","og_url":"https:\/\/www.abpon.com\/product\/\u0e02\u0e49\u0e2d\u0e07\u0e2d\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21-jef-sus31610-45\u0e2d\u0e07\u0e28\u0e32-041645-600\/","og_site_name":"Abpon","article_modified_time":"2024-03-25T05:57:45+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abpon.com\/product\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\/","url":"https:\/\/www.abpon.com\/product\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\/","name":"Elbow\u00a045degree\u00a0SUS\u00a0316\u00a0#10\u00a06\" - Abpon","isPartOf":{"@id":"https:\/\/www.abpon.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abpon.com\/product\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\/#primaryimage"},"image":{"@id":"https:\/\/www.abpon.com\/product\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abpon.com\/wp-content\/uploads\/041645-600.png","datePublished":"2024-03-25T05:51:17+00:00","dateModified":"2024-03-25T05:57:45+00:00","breadcrumb":{"@id":"https:\/\/www.abpon.com\/product\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abpon.com\/product\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.abpon.com\/product\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\/#primaryimage","url":"https:\/\/www.abpon.com\/wp-content\/uploads\/041645-600.png","contentUrl":"https:\/\/www.abpon.com\/wp-content\/uploads\/041645-600.png","width":600,"height":600,"caption":"041645 600"},{"@type":"BreadcrumbList","@id":"https:\/\/www.abpon.com\/product\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1-jef-sus31610-45%e0%b8%ad%e0%b8%87%e0%b8%a8%e0%b8%b2-041645-600\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abpon.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.abpon.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Elbow\u00a045degree\u00a0SUS\u00a0316\u00a0#10\u00a06&#8243;"}]},{"@type":"WebSite","@id":"https:\/\/www.abpon.com\/#website","url":"https:\/\/www.abpon.com\/","name":"Abpon","description":"","publisher":{"@id":"https:\/\/www.abpon.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abpon.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.abpon.com\/#organization","name":"Abpon","url":"https:\/\/www.abpon.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.abpon.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.abpon.com\/wp-content\/uploads\/09-abpon-logo-removebg-preview.png","contentUrl":"https:\/\/www.abpon.com\/wp-content\/uploads\/09-abpon-logo-removebg-preview.png","width":276,"height":183,"caption":"Abpon"},"image":{"@id":"https:\/\/www.abpon.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.abpon.com\/en\/wp-json\/wp\/v2\/product\/9157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abpon.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.abpon.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abpon.com\/en\/wp-json\/wp\/v2\/comments?post=9157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abpon.com\/en\/wp-json\/wp\/v2\/media\/89338"}],"wp:attachment":[{"href":"https:\/\/www.abpon.com\/en\/wp-json\/wp\/v2\/media?parent=9157"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.abpon.com\/en\/wp-json\/wp\/v2\/product_brand?post=9157"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.abpon.com\/en\/wp-json\/wp\/v2\/product_cat?post=9157"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.abpon.com\/en\/wp-json\/wp\/v2\/product_tag?post=9157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}